{"id":1486,"date":"2020-12-04T21:21:57","date_gmt":"2020-12-04T17:51:57","guid":{"rendered":"http:\/\/beskin.ir\/shop\/?page_id=1486"},"modified":"2026-04-13T12:35:36","modified_gmt":"2026-04-13T09:05:36","slug":"form","status":"publish","type":"page","link":"https:\/\/beskin.ir\/shop\/form\/","title":{"rendered":"\u0641\u0631\u0645 \u0645\u0634\u0627\u0648\u0631\u0647 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648"},"content":{"rendered":"<div id=\"quform-a40ede\" class=\"quform quform-1 quform-rtl quform-support-page-caching quform-is-first-page\"><form id=\"quform-form-a40ede\" class=\"quform-form quform-form-1\" action=\"\/shop\/wp-json\/wp\/v2\/pages\/1486#quform-a40ede\" method=\"post\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-options=\"{&quot;id&quot;:1,&quot;uniqueId&quot;:&quot;a40ede&quot;,&quot;theme&quot;:&quot;&quot;,&quot;ajax&quot;:true,&quot;logic&quot;:{&quot;logic&quot;:{&quot;46&quot;:{&quot;action&quot;:true,&quot;match&quot;:&quot;all&quot;,&quot;rules&quot;:[{&quot;elementId&quot;:&quot;45&quot;,&quot;operator&quot;:&quot;eq&quot;,&quot;optionId&quot;:&quot;1&quot;,&quot;value&quot;:&quot;\\u0628\\u0644\\u06cc&quot;}]},&quot;55&quot;:{&quot;action&quot;:true,&quot;match&quot;:&quot;all&quot;,&quot;rules&quot;:[{&quot;elementId&quot;:&quot;48&quot;,&quot;operator&quot;:&quot;eq&quot;,&quot;optionId&quot;:&quot;1&quot;,&quot;value&quot;:&quot;\\u0628\\u0644\\u06cc&quot;}]},&quot;57&quot;:{&quot;action&quot;:true,&quot;match&quot;:&quot;all&quot;,&quot;rules&quot;:[{&quot;elementId&quot;:&quot;48&quot;,&quot;operator&quot;:&quot;eq&quot;,&quot;optionId&quot;:&quot;1&quot;,&quot;value&quot;:&quot;\\u0628\\u0644\\u06cc&quot;}]},&quot;56&quot;:{&quot;action&quot;:true,&quot;match&quot;:&quot;all&quot;,&quot;rules&quot;:[{&quot;elementId&quot;:&quot;48&quot;,&quot;operator&quot;:&quot;eq&quot;,&quot;optionId&quot;:&quot;1&quot;,&quot;value&quot;:&quot;\\u0628\\u0644\\u06cc&quot;}]}},&quot;dependents&quot;:{&quot;45&quot;:[46],&quot;48&quot;:[55,57,56]},&quot;elementIds&quot;:[46,55,57,56],&quot;dependentElementIds&quot;:[&quot;45&quot;,&quot;48&quot;],&quot;animate&quot;:true},&quot;currentPageId&quot;:1,&quot;errorsIcon&quot;:&quot;&quot;,&quot;updateFancybox&quot;:true,&quot;hasPages&quot;:true,&quot;pages&quot;:[1,23,42,59,62,69,81],&quot;pageProgressType&quot;:&quot;numbers&quot;,&quot;tooltipsEnabled&quot;:true,&quot;tooltipClasses&quot;:&quot;qtip-quform-dark qtip-shadow&quot;,&quot;tooltipMy&quot;:&quot;left center&quot;,&quot;tooltipAt&quot;:&quot;right center&quot;,&quot;isRtl&quot;:true,&quot;scrollOffset&quot;:-50,&quot;scrollSpeed&quot;:800}\"><button class=\"quform-default-submit\" name=\"quform_submit\" type=\"submit\" value=\"submit\" aria-hidden=\"true\" tabindex=\"-1\"><\/button><div class=\"quform-form-inner quform-form-inner-1\"><input type=\"hidden\" name=\"quform_form_id\" value=\"1\" \/><input type=\"hidden\" name=\"quform_form_uid\" value=\"a40ede\" \/><input type=\"hidden\" name=\"quform_count\" value=\"1\" \/><input type=\"hidden\" name=\"form_url\" value=\"https:\/\/beskin.ir\/shop\/wp-json\/wp\/v2\/pages\/1486\" \/><input type=\"hidden\" name=\"referring_url\" value=\"\" \/><input type=\"hidden\" name=\"post_id\" value=\"\" \/><input type=\"hidden\" name=\"post_title\" value=\"\" \/><input type=\"hidden\" name=\"quform_current_page_id\" value=\"1\" \/><input type=\"hidden\" name=\"quform_csrf_token\" value=\"X4N1Ce6vo3LSof3cNfMM8LkaU15QdMTCQg1fDavI\" \/><div class=\"quform-elements quform-elements-1 quform-cf quform-responsive-elements-phone-landscape\"><div class=\"quform-page-progress quform-page-progress-type-numbers\"><div class=\"quform-page-progress-bar\" style=\"width: 14%;\"><span class=\"quform-page-progress-text\">\u0635\u0641\u062d\u0647 <span class=\"quform-page-progress-number\">1<\/span> \u0627\u0632 7<\/span><\/div><\/div><div class=\"quform-element quform-element-page quform-page-1 quform-page-1_1 quform-cf quform-group-style-plain quform-first-page quform-current-page\"><div class=\"quform-page-title-description\"><h4 class=\"quform-page-title\">\u0644\u0637\u0641\u0627 \u062c\u0647\u062a \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u0634\u0627\u0648\u0631\u0647\u060c \u0633\u0648\u0627\u0644\u0627\u062a \u0632\u06cc\u0631 \u0631\u0627 \u0628\u0627 \u062f\u0642\u062a \u067e\u0627\u0633\u062e \u062f\u0647\u06cc\u062f<\/h4><p class=\"quform-page-description\">\u00a0\n\u00a0\n\u00a0<\/p><\/div><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-row quform-element-row-1_3 quform-4-columns quform-element-row-size-fixed quform-responsive-columns-phone-landscape\"><div class=\"quform-element quform-element-column quform-element-1_4\"><div class=\"quform-element quform-element-text quform-element-1_8 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_8\"><label class=\"quform-label-text\" for=\"quform_1_8_a40ede\">\u0646\u0627\u0645 \u0648 \u0646\u0627\u0645 \u062e\u0627\u0646\u0648\u0627\u062f\u06af\u06cc<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_8\"><div class=\"quform-input quform-input-text quform-input-1_8 quform-cf\"><input type=\"text\" id=\"quform_1_8_a40ede\" name=\"quform_1_8\" class=\"quform-field quform-field-text quform-field-1_8\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-1_5\"><div class=\"quform-element quform-element-text quform-element-1_10 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_10\"><label class=\"quform-label-text\" for=\"quform_1_10_a40ede\">\u0634\u0645\u0627\u0631\u0647 \u062a\u0645\u0627\u0633<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_10\"><div class=\"quform-input quform-input-text quform-input-1_10 quform-cf\"><input type=\"text\" id=\"quform_1_10_a40ede\" name=\"quform_1_10\" class=\"quform-field quform-field-text quform-field-1_10\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-1_6\"><div class=\"quform-element quform-element-text quform-element-1_9 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_9\"><label class=\"quform-label-text\" for=\"quform_1_9_a40ede\">\u0633\u0646<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_9\"><div class=\"quform-input quform-input-text quform-input-1_9 quform-cf\"><input type=\"text\" id=\"quform_1_9_a40ede\" name=\"quform_1_9\" class=\"quform-field quform-field-text quform-field-1_9\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-1_7\"><div class=\"quform-element quform-element-text quform-element-1_11 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_11\"><label class=\"quform-label-text\" for=\"quform_1_11_a40ede\">\u0634\u063a\u0644 ( \u0627\u062e\u062a\u06cc\u0627\u0631\u06cc)<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_11\"><div class=\"quform-input quform-input-text quform-input-1_11 quform-cf\"><input type=\"text\" id=\"quform_1_11_a40ede\" name=\"quform_1_11\" class=\"quform-field quform-field-text quform-field-1_11\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-row quform-element-row-1_14 quform-2-columns quform-element-row-size-fixed quform-responsive-columns-phone-landscape\"><div class=\"quform-element quform-element-column quform-element-1_15\"><div class=\"quform-element quform-element-text quform-element-1_12 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_12\"><label class=\"quform-label-text\" for=\"quform_1_12_a40ede\">\u0634\u0647\u0631 \u0645\u062d\u0644 \u0633\u06a9\u0648\u0646\u062a<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_12\"><div class=\"quform-input quform-input-text quform-input-1_12 quform-cf\"><input type=\"text\" id=\"quform_1_12_a40ede\" name=\"quform_1_12\" class=\"quform-field quform-field-text quform-field-1_12\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-1_16\"><div class=\"quform-element quform-element-text quform-element-1_17 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_17\"><label class=\"quform-label-text\" for=\"quform_1_17_a40ede\">\u06a9\u062f \u0645\u0644\u06cc \u062c\u0647\u062a \u0634\u0631\u06a9\u062a \u062f\u0631 \u0642\u0631\u0639\u0647 \u06a9\u0634\u06cc (\u0627\u062e\u062a\u06cc\u0627\u0631\u06cc)<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_17\"><div class=\"quform-input quform-input-text quform-input-1_17 quform-cf\"><input type=\"text\" id=\"quform_1_17_a40ede\" name=\"quform_1_17\" class=\"quform-field quform-field-text quform-field-1_17\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-1_2 quform-cf quform-button-style-theme\"><div class=\"quform-button-next quform-button-next-default quform-button-next-1_2\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-next\" value=\"submit\"><span class=\"quform-button-text quform-button-next-text\">\u0628\u0639\u062f\u06cc<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-page quform-page-23 quform-page-1_23 quform-cf quform-group-style-plain\"><div class=\"quform-page-title-description\"><h4 class=\"quform-page-title\">\u0647\u062f\u0641 \u0627\u0632 \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u0634\u0627\u0648\u0631\u0647<\/h4><p class=\"quform-page-description\">\u00a0\n\u00a0\n\u00a0\n<\/p><\/div><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-checkbox quform-element-1_39 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_39\"><label class=\"quform-label-text\" id=\"quform_1_39_a40ede_label\">\u0647\u062f\u0641 \u0634\u0645\u0627 \u0627\u0632 \u0645\u0634\u0627\u0648\u0631\u0647 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648 \u0686\u06cc\u0633\u062a\u061f ( \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0686\u0646\u062f\u06cc\u0646 \u0645\u0648\u0631\u062f \u0631\u0627 \u0639\u0644\u0627\u0645\u062a \u0628\u0632\u0646\u06cc\u062f)<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-checkbox quform-inner-1_39\"><div class=\"quform-input quform-input-checkbox quform-input-1_39 quform-cf\"><div class=\"quform-options quform-cf quform-options-block quform-options-simple\" role=\"group\" aria-labelledby=\"quform_1_39_a40ede_label\"><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_39[]\" id=\"quform_1_39_a40ede_1\" class=\"quform-field quform-field-checkbox quform-field-1_39 quform-field-1_39_1\" value=\"\u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0622\u0631\u0627\u06cc\u0634\u06cc \u0648 \u0628\u0647\u062f\u0627\u0634\u062a\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0627 \u067e\u0648\u0633\u062a \u062e\u0648\u062f\u0645\" \/><label for=\"quform_1_39_a40ede_1\" class=\"quform-option-label quform-option-label-1_39_1\"><span class=\"quform-option-text\">\u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0622\u0631\u0627\u06cc\u0634\u06cc \u0648 \u0628\u0647\u062f\u0627\u0634\u062a\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0627 \u067e\u0648\u0633\u062a \u062e\u0648\u062f\u0645<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_39[]\" id=\"quform_1_39_a40ede_2\" class=\"quform-field quform-field-checkbox quform-field-1_39 quform-field-1_39_2\" value=\"\u062c\u0648\u0627\u0646\u0633\u0627\u0632\u06cc \u0648 \u0645\u0631\u0627\u0642\u0628\u062a \u0627\u0632 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648\" \/><label for=\"quform_1_39_a40ede_2\" class=\"quform-option-label quform-option-label-1_39_2\"><span class=\"quform-option-text\">\u062c\u0648\u0627\u0646\u0633\u0627\u0632\u06cc \u0648 \u0645\u0631\u0627\u0642\u0628\u062a \u0627\u0632 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_39[]\" id=\"quform_1_39_a40ede_3\" class=\"quform-field quform-field-checkbox quform-field-1_39 quform-field-1_39_3\" value=\"\u0631\u0641\u0639 \u0686\u06cc\u0646 \u0648 \u0686\u0631\u0648\u06a9 \u0648 \u067e\u06cc\u0631\u06cc \u067e\u0648\u0633\u062a\" \/><label for=\"quform_1_39_a40ede_3\" class=\"quform-option-label quform-option-label-1_39_3\"><span class=\"quform-option-text\">\u0631\u0641\u0639 \u0686\u06cc\u0646 \u0648 \u0686\u0631\u0648\u06a9 \u0648 \u067e\u06cc\u0631\u06cc \u067e\u0648\u0633\u062a<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_39[]\" id=\"quform_1_39_a40ede_8\" class=\"quform-field quform-field-checkbox quform-field-1_39 quform-field-1_39_8\" value=\"\u062f\u0631\u0645\u0627\u0646 \u0686\u0631\u0628\u06cc\u060c \u0634\u0648\u0631\u0647 \u0648 \u0631\u06cc\u0632\u0634 \u0645\u0648\" \/><label for=\"quform_1_39_a40ede_8\" class=\"quform-option-label quform-option-label-1_39_8\"><span class=\"quform-option-text\">\u062f\u0631\u0645\u0627\u0646 \u0686\u0631\u0628\u06cc\u060c \u0634\u0648\u0631\u0647 \u0648 \u0631\u06cc\u0632\u0634 \u0645\u0648<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_39[]\" id=\"quform_1_39_a40ede_7\" class=\"quform-field quform-field-checkbox quform-field-1_39 quform-field-1_39_7\" value=\"\u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u062f\u0646 \u062c\u0627\u06cc \u062c\u0648\u0634 \u0648 \u0644\u06a9 \u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc\" \/><label for=\"quform_1_39_a40ede_7\" class=\"quform-option-label quform-option-label-1_39_7\"><span class=\"quform-option-text\">\u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u062f\u0646 \u062c\u0627\u06cc \u062c\u0648\u0634 \u0648 \u0644\u06a9 \u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_39[]\" id=\"quform_1_39_a40ede_6\" class=\"quform-field quform-field-checkbox quform-field-1_39 quform-field-1_39_6\" value=\"\u0631\u0641\u0639 \u0639\u0644\u0627\u0626\u0645 \u062d\u0633\u0627\u0633\u06cc\u062a \u067e\u0648\u0633\u062a\u06cc \u0648 \u0627\u06af\u0632\u0645\u0627\" \/><label for=\"quform_1_39_a40ede_6\" class=\"quform-option-label quform-option-label-1_39_6\"><span class=\"quform-option-text\">\u0631\u0641\u0639 \u0639\u0644\u0627\u0626\u0645 \u062d\u0633\u0627\u0633\u06cc\u062a \u067e\u0648\u0633\u062a\u06cc \u0648 \u0627\u06af\u0632\u0645\u0627<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_39[]\" id=\"quform_1_39_a40ede_5\" class=\"quform-field quform-field-checkbox quform-field-1_39 quform-field-1_39_5\" value=\"\u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u062f\u0646 \u062c\u0648\u0634 \u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc\" \/><label for=\"quform_1_39_a40ede_5\" class=\"quform-option-label quform-option-label-1_39_5\"><span class=\"quform-option-text\">\u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u062f\u0646 \u062c\u0648\u0634 \u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_39[]\" id=\"quform_1_39_a40ede_4\" class=\"quform-field quform-field-checkbox quform-field-1_39 quform-field-1_39_4\" value=\"\u0631\u0641\u0639 \u062e\u0634\u06a9\u06cc \u0648 \u062f\u0647\u06cc\u062f\u0631\u0627\u062a\u0647 \u0634\u062f\u0646 \u067e\u0648\u0633\u062a\" \/><label for=\"quform_1_39_a40ede_4\" class=\"quform-option-label quform-option-label-1_39_4\"><span class=\"quform-option-text\">\u0631\u0641\u0639 \u062e\u0634\u06a9\u06cc \u0648 \u062f\u0647\u06cc\u062f\u0631\u0627\u062a\u0647 \u0634\u062f\u0646 \u067e\u0648\u0633\u062a<\/span><\/label><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-1_40 quform-cf quform-button-style-theme\"><div class=\"quform-button-back quform-button-back-default quform-button-back-1_40\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-back\" value=\"back\"><span class=\"quform-button-text quform-button-back-text\">\u0628\u0631\u06af\u0634\u062a<\/span><\/button><\/div><div class=\"quform-button-next quform-button-next-default quform-button-next-1_40\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-next\" value=\"submit\"><span class=\"quform-button-text quform-button-next-text\">\u0628\u0639\u062f\u06cc<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-page quform-page-42 quform-page-1_42 quform-cf quform-group-style-plain\"><div class=\"quform-page-title-description\"><h4 class=\"quform-page-title\">\u0628\u0627 \u067e\u0627\u0633\u062e \u062f\u0627\u062f\u0646 \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u0632\u06cc\u0631 \u0628\u0647 \u0645\u0634\u0627\u0648\u0631\u062a\u0627\u0646 \u062c\u0647\u062a \u0627\u0631\u0627\u06cc\u0647 \u0645\u0634\u0627\u0648\u0631\u0647 \u0627\u06cc \u0628\u0647\u062a\u0631 \u06a9\u0645\u06a9 \u0641\u0631\u0645\u0627\u06cc\u06cc\u062f<\/h4><p class=\"quform-page-description\">\u00a0\n\u00a0\n\u00a0\n<\/p><\/div><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-select quform-element-1_45 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_45\"><label class=\"quform-label-text\" for=\"quform_1_45_a40ede\">\u0622\u06cc\u0627 \u062a\u0627 \u06a9\u0646\u0648\u0646 \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0646\u0638\u0645 \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0645\u0631\u0627\u0642\u0628\u062a \u0627\u0632 \u067e\u0648\u0633\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f\u06cc\u062f\u061f<\/label><\/div><div class=\"quform-inner quform-inner-select quform-inner-1_45\"><div class=\"quform-input quform-input-select quform-input-1_45 quform-cf\"><select id=\"quform_1_45_a40ede\" name=\"quform_1_45\" class=\"quform-field quform-field-select quform-field-1_45\"><option value=\"\" selected=\"selected\">\u0644\u0637\u0641\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f<\/option><option value=\"\u0628\u0644\u06cc\">\u0628\u0644\u06cc<\/option><option value=\"\u062e\u06cc\u0631\">\u062e\u06cc\u0631<\/option><\/select><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-text quform-element-1_46 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_46\"><label class=\"quform-label-text\" for=\"quform_1_46_a40ede\">\u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0631\u0627 \u0628\u0646\u0648\u06cc\u0633\u06cc\u062f<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_46\"><div class=\"quform-input quform-input-text quform-input-1_46 quform-cf\"><input type=\"text\" id=\"quform_1_46_a40ede\" name=\"quform_1_46\" class=\"quform-field quform-field-text quform-field-1_46\" \/><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-select quform-element-1_47 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_47\"><label class=\"quform-label-text\" for=\"quform_1_47_a40ede\">\u0622\u06cc\u0627  \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u062a\u062d\u062a \u0646\u0638\u0631 \u067e\u0632\u0634\u06a9 \u0645\u062a\u062e\u0635\u0635\u0635 \u0647\u0633\u062a\u06cc\u062f\u061f<\/label><\/div><div class=\"quform-inner quform-inner-select quform-inner-1_47\"><div class=\"quform-input quform-input-select quform-input-1_47 quform-cf\"><select id=\"quform_1_47_a40ede\" name=\"quform_1_47\" class=\"quform-field quform-field-select quform-field-1_47\"><option value=\"\" selected=\"selected\">\u0644\u0637\u0641\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f<\/option><option value=\"\u0628\u0644\u06cc\">\u0628\u0644\u06cc<\/option><option value=\"\u062e\u06cc\u0631\">\u062e\u06cc\u0631<\/option><\/select><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-select quform-element-1_48 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_48\"><label class=\"quform-label-text\" for=\"quform_1_48_a40ede\">\u0622\u06cc\u0627 \u0628\u0631\u0627\u06cc \u067e\u0648\u0633\u062a \u06cc\u0627 \u0645\u0648\u06cc \u062e\u0648\u062f \u062f\u0627\u0631\u0648 \u0645\u0635\u0631\u0641 \u0645\u06cc \u06a9\u0646\u06cc\u062f\u061f<\/label><\/div><div class=\"quform-inner quform-inner-select quform-inner-1_48\"><div class=\"quform-input quform-input-select quform-input-1_48 quform-cf\"><select id=\"quform_1_48_a40ede\" name=\"quform_1_48\" class=\"quform-field quform-field-select quform-field-1_48\"><option value=\"\" selected=\"selected\">\u0644\u0637\u0641\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f<\/option><option value=\"\u0628\u0644\u06cc\">\u0628\u0644\u06cc<\/option><option value=\"\u062e\u06cc\u0631\">\u062e\u06cc\u0631<\/option><\/select><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-row quform-element-row-1_49 quform-3-columns quform-element-row-size-fixed quform-responsive-columns-phone-landscape\"><div class=\"quform-element quform-element-column quform-element-1_50\"><div class=\"quform-element quform-element-text quform-element-1_55 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_55\"><label class=\"quform-label-text\" for=\"quform_1_55_a40ede\">\u0646\u0627\u0645 \u062f\u0627\u0631\u0648<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_55\"><div class=\"quform-input quform-input-text quform-input-1_55 quform-cf\"><input type=\"text\" id=\"quform_1_55_a40ede\" name=\"quform_1_55\" class=\"quform-field quform-field-text quform-field-1_55\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-1_51\"><div class=\"quform-element quform-element-text quform-element-1_57 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_57\"><label class=\"quform-label-text\" for=\"quform_1_57_a40ede\">\u0639\u0644\u062a \u0645\u0635\u0631\u0641 \u062f\u0627\u0631\u0648<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_57\"><div class=\"quform-input quform-input-text quform-input-1_57 quform-cf\"><input type=\"text\" id=\"quform_1_57_a40ede\" name=\"quform_1_57\" class=\"quform-field quform-field-text quform-field-1_57\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-1_52\"><div class=\"quform-element quform-element-text quform-element-1_56 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_56\"><label class=\"quform-label-text\" for=\"quform_1_56_a40ede\">\u062f\u0648\u0631\u0647 \u0645\u0635\u0631\u0641 \u062f\u0627\u0631\u0648<\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_56\"><div class=\"quform-input quform-input-text quform-input-1_56 quform-cf\"><input type=\"text\" id=\"quform_1_56_a40ede\" name=\"quform_1_56\" class=\"quform-field quform-field-text quform-field-1_56\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-text quform-element-1_58 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_58\"><label class=\"quform-label-text\" for=\"quform_1_58_a40ede\">\u0628\u0631\u0627\u06cc \u0634\u0633\u062a \u0648 \u0634\u0648\u06cc \u067e\u0648\u0633\u062a \u0635\u0648\u0631\u062a \u0648 \u0628\u062f\u0646 \u062e\u0648\u062f \u0627\u0632 \u0686\u0647 \u0645\u062d\u0635\u0648\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u06cc\u062f\u061f<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-text quform-inner-1_58\"><div class=\"quform-input quform-input-text quform-input-1_58 quform-cf\"><input type=\"text\" id=\"quform_1_58_a40ede\" name=\"quform_1_58\" class=\"quform-field quform-field-text quform-field-1_58\" \/><\/div><p class=\"quform-description quform-description-below\">\u0628\u0647 \u0637\u0648\u0631 \u0645\u062b\u0627\u0644: \u0698\u0644 \u0634\u0633\u062a\u0634\u0648 \u06cc\u0627 \u0635\u0627\u0628\u0648\u0646 \u0648...<\/p><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-1_44 quform-cf quform-button-style-theme\"><div class=\"quform-button-back quform-button-back-default quform-button-back-1_44\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-back\" value=\"back\"><span class=\"quform-button-text quform-button-back-text\">\u0628\u0631\u06af\u0634\u062a<\/span><\/button><\/div><div class=\"quform-button-next quform-button-next-default quform-button-next-1_44\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-next\" value=\"submit\"><span class=\"quform-button-text quform-button-next-text\">\u0628\u0639\u062f\u06cc<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-page quform-page-59 quform-page-1_59 quform-cf quform-group-style-plain\"><div class=\"quform-page-title-description\"><h4 class=\"quform-page-title\">\u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0627\u0632 \u062d\u0627\u0644\u0627\u062a \u0632\u06cc\u0631 \u067e\u0648\u0633\u062a \u0634\u0645\u0627 \u0631\u0627 \u062a\u0648\u0635\u06cc\u0641 \u0645\u06cc \u06a9\u0646\u062f\u061f<\/h4><p class=\"quform-page-description\">\u00a0\n\u00a0\n\u00a0\n<\/p><\/div><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-checkbox quform-element-1_60 quform-cf quform-element-required\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_60\"><label class=\"quform-label-text\" id=\"quform_1_60_a40ede_label\">( \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0686\u0646\u062f\u06cc\u0646 \u0645\u0648\u0631\u062f \u0631\u0627 \u0639\u0644\u0627\u0645\u062a \u0628\u0632\u0646\u06cc\u062f)<span class=\"quform-required\">*<\/span><\/label><\/div><div class=\"quform-inner quform-inner-checkbox quform-inner-1_60\"><div class=\"quform-input quform-input-checkbox quform-input-1_60 quform-cf\"><div class=\"quform-options quform-cf quform-options-block quform-options-simple\" role=\"group\" aria-labelledby=\"quform_1_60_a40ede_label\"><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_60[]\" id=\"quform_1_60_a40ede_1\" class=\"quform-field quform-field-checkbox quform-field-1_60 quform-field-1_60_1\" value=\"\u0627\u062d\u0633\u0627\u0633 \u062e\u0634\u06a9\u06cc \u0648 \u06a9\u0634\u06cc\u062f\u06af\u06cc \u067e\u0648\u0633\u062a\" \/><label for=\"quform_1_60_a40ede_1\" class=\"quform-option-label quform-option-label-1_60_1\"><span class=\"quform-option-text\">\u0627\u062d\u0633\u0627\u0633 \u062e\u0634\u06a9\u06cc \u0648 \u06a9\u0634\u06cc\u062f\u06af\u06cc \u067e\u0648\u0633\u062a<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_60[]\" id=\"quform_1_60_a40ede_2\" class=\"quform-field quform-field-checkbox quform-field-1_60 quform-field-1_60_2\" value=\"\u067e\u0648\u0633\u062a\u0647 \u067e\u0648\u0633\u062a\u0647 \u0634\u062f\u0646 \u062f\u0631 \u0641\u0635\u0644 \u0633\u0631\u0645\u0627\" \/><label for=\"quform_1_60_a40ede_2\" class=\"quform-option-label quform-option-label-1_60_2\"><span class=\"quform-option-text\">\u067e\u0648\u0633\u062a\u0647 \u067e\u0648\u0633\u062a\u0647 \u0634\u062f\u0646 \u062f\u0631 \u0641\u0635\u0644 \u0633\u0631\u0645\u0627<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_60[]\" id=\"quform_1_60_a40ede_3\" class=\"quform-field quform-field-checkbox quform-field-1_60 quform-field-1_60_3\" value=\"\u0686\u0631\u0628 \u0634\u062f\u0646 \u0633\u0631\u06cc\u0639 \u067e\u0648\u0633\u062a \u0648 \u0645\u0646\u0627\u0641\u0630 \u0628\u0627\u0632\" \/><label for=\"quform_1_60_a40ede_3\" class=\"quform-option-label quform-option-label-1_60_3\"><span class=\"quform-option-text\">\u0686\u0631\u0628 \u0634\u062f\u0646 \u0633\u0631\u06cc\u0639 \u067e\u0648\u0633\u062a \u0648 \u0645\u0646\u0627\u0641\u0630 \u0628\u0627\u0632<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_60[]\" id=\"quform_1_60_a40ede_8\" class=\"quform-field quform-field-checkbox quform-field-1_60 quform-field-1_60_8\" value=\"\u0631\u0648\u06cc \u0628\u06cc\u0646\u06cc \u0648 \u067e\u06cc\u0634\u0627\u0646\u06cc \u0627\u062d\u0633\u0627\u0633 \u0686\u0631\u0628\u06cc \u0648 \u0631\u0648\u06cc \u06af\u0648\u0646\u0647 \u0627\u062d\u0633\u0627\u0633 \u062e\u0634\u06a9\u06cc \u062f\u0627\u0631\u0645 \u06cc\u0627 \u0628\u0627\u0644\u0639\u06a9\u0633\" \/><label for=\"quform_1_60_a40ede_8\" class=\"quform-option-label quform-option-label-1_60_8\"><span class=\"quform-option-text\">\u0631\u0648\u06cc \u0628\u06cc\u0646\u06cc \u0648 \u067e\u06cc\u0634\u0627\u0646\u06cc \u0627\u062d\u0633\u0627\u0633 \u0686\u0631\u0628\u06cc \u0648 \u0631\u0648\u06cc \u06af\u0648\u0646\u0647 \u0627\u062d\u0633\u0627\u0633 \u062e\u0634\u06a9\u06cc \u062f\u0627\u0631\u0645 \u06cc\u0627 \u0628\u0627\u0644\u0639\u06a9\u0633<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_60[]\" id=\"quform_1_60_a40ede_7\" class=\"quform-field quform-field-checkbox quform-field-1_60 quform-field-1_60_7\" value=\"\u067e\u0648\u0633\u062a \u062d\u0633\u0627\u0633\u06cc \u062f\u0627\u0631\u0645 ( \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0622\u0641\u062a\u0627\u0628 \u06cc\u0627 \u0628\u0631\u062e\u06cc \u062e\u0648\u0631\u0627\u06a9\u06cc \u0647\u0627 \u0648\u0627\u06a9\u0646\u0634 \u062f\u0627\u062f\u0647 \u0648 \u0627\u062d\u0633\u0627\u0633 \u062e\u0627\u0631\u0634 \u0648 \u0633\u0648\u0632\u0634 \u0645\u06cc \u06a9\u0646\u0645)\" \/><label for=\"quform_1_60_a40ede_7\" class=\"quform-option-label quform-option-label-1_60_7\"><span class=\"quform-option-text\">\u067e\u0648\u0633\u062a \u062d\u0633\u0627\u0633\u06cc \u062f\u0627\u0631\u0645 ( \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0622\u0641\u062a\u0627\u0628 \u06cc\u0627 \u0628\u0631\u062e\u06cc \u062e\u0648\u0631\u0627\u06a9\u06cc \u0647\u0627 \u0648\u0627\u06a9\u0646\u0634 \u062f\u0627\u062f\u0647 \u0648 \u0627\u062d\u0633\u0627\u0633 \u062e\u0627\u0631\u0634 \u0648 \u0633\u0648\u0632\u0634 \u0645\u06cc \u06a9\u0646\u0645)<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_60[]\" id=\"quform_1_60_a40ede_6\" class=\"quform-field quform-field-checkbox quform-field-1_60 quform-field-1_60_6\" value=\"\u0647\u06cc\u0686 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0641\u0648\u0642 \u0631\u0627 \u0631\u0648\u06cc \u067e\u0648\u0633\u062a \u062e\u0648\u062f \u0646\u062f\u0627\u0631\u0645\" \/><label for=\"quform_1_60_a40ede_6\" class=\"quform-option-label quform-option-label-1_60_6\"><span class=\"quform-option-text\">\u0647\u06cc\u0686 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0641\u0648\u0642 \u0631\u0627 \u0631\u0648\u06cc \u067e\u0648\u0633\u062a \u062e\u0648\u062f \u0646\u062f\u0627\u0631\u0645<\/span><\/label><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-1_61 quform-cf quform-button-style-theme\"><div class=\"quform-button-back quform-button-back-default quform-button-back-1_61\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-back\" value=\"back\"><span class=\"quform-button-text quform-button-back-text\">\u0628\u0631\u06af\u0634\u062a<\/span><\/button><\/div><div class=\"quform-button-next quform-button-next-default quform-button-next-1_61\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-next\" value=\"submit\"><span class=\"quform-button-text quform-button-next-text\">\u0628\u0639\u062f\u06cc<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-page quform-page-62 quform-page-1_62 quform-cf quform-group-style-plain\"><div class=\"quform-page-title-description\"><h4 class=\"quform-page-title\">\u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0631\u0627 \u0631\u0648\u06cc \u067e\u0648\u0633\u062a \u062e\u0648\u062f \u0627\u062d\u0633\u0627\u0633 \u0645\u06cc \u06a9\u0646\u06cc\u062f\u061f<\/h4><p class=\"quform-page-description\">\u00a0\n\u00a0\n\u00a0\n<\/p><\/div><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-row quform-element-row-1_65 quform-2-columns quform-element-row-size-fixed quform-responsive-columns-phone-landscape\"><div class=\"quform-element quform-element-column quform-element-1_66\"><div class=\"quform-element quform-element-checkbox quform-element-1_63 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-inner quform-inner-checkbox quform-inner-1_63\"><div class=\"quform-input quform-input-checkbox quform-input-1_63 quform-cf\"><div class=\"quform-options quform-cf quform-options-block quform-options-simple\"><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_63[]\" id=\"quform_1_63_a40ede_1\" class=\"quform-field quform-field-checkbox quform-field-1_63 quform-field-1_63_1\" value=\"\u0627\u062d\u0633\u0627\u0633 \u0634\u0644 \u0634\u062f\u06af\u06cc \u0648 \u06cc\u0627 \u0686\u06cc\u0646 \u0648 \u0686\u0631\u0648\u06a9 \u067e\u0648\u0633\u062a \u0635\u0648\u0631\u062a\" \/><label for=\"quform_1_63_a40ede_1\" class=\"quform-option-label quform-option-label-1_63_1\"><span class=\"quform-option-text\">\u0627\u062d\u0633\u0627\u0633 \u0634\u0644 \u0634\u062f\u06af\u06cc \u0648 \u06cc\u0627 \u0686\u06cc\u0646 \u0648 \u0686\u0631\u0648\u06a9 \u067e\u0648\u0633\u062a \u0635\u0648\u0631\u062a<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_63[]\" id=\"quform_1_63_a40ede_2\" class=\"quform-field quform-field-checkbox quform-field-1_63 quform-field-1_63_2\" value=\"\u062e\u0634\u06a9\u06cc \u067e\u0648\u0633\u062a \u0635\u0648\u0631\u062a\" \/><label for=\"quform_1_63_a40ede_2\" class=\"quform-option-label quform-option-label-1_63_2\"><span class=\"quform-option-text\">\u062e\u0634\u06a9\u06cc \u067e\u0648\u0633\u062a \u0635\u0648\u0631\u062a<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_63[]\" id=\"quform_1_63_a40ede_3\" class=\"quform-field quform-field-checkbox quform-field-1_63 quform-field-1_63_3\" value=\"\u062c\u0648\u0634 \u0647\u0627\u06cc \u0632\u06cc\u0631 \u067e\u0648\u0633\u062a\u06cc \u0635\u0648\u0631\u062a\" \/><label for=\"quform_1_63_a40ede_3\" class=\"quform-option-label quform-option-label-1_63_3\"><span class=\"quform-option-text\">\u062c\u0648\u0634 \u0647\u0627\u06cc \u0632\u06cc\u0631 \u067e\u0648\u0633\u062a\u06cc \u0635\u0648\u0631\u062a<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_63[]\" id=\"quform_1_63_a40ede_8\" class=\"quform-field quform-field-checkbox quform-field-1_63 quform-field-1_63_8\" value=\"\u062c\u0648\u0634 \u0647\u0627\u06cc \u0633\u0631 \u0633\u06cc\u0627\u0647 \u0648 \u0633\u0631 \u0633\u0641\u06cc\u062f \u0648 \u06cc\u0627 \u0627\u0644\u062a\u0647\u0627\u0628\u06cc \u0635\u0648\u0631\u062a\" \/><label for=\"quform_1_63_a40ede_8\" class=\"quform-option-label quform-option-label-1_63_8\"><span class=\"quform-option-text\">\u062c\u0648\u0634 \u0647\u0627\u06cc \u0633\u0631 \u0633\u06cc\u0627\u0647 \u0648 \u0633\u0631 \u0633\u0641\u06cc\u062f \u0648 \u06cc\u0627 \u0627\u0644\u062a\u0647\u0627\u0628\u06cc \u0635\u0648\u0631\u062a<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_63[]\" id=\"quform_1_63_a40ede_7\" class=\"quform-field quform-field-checkbox quform-field-1_63 quform-field-1_63_7\" value=\"\u0645\u0646\u0627\u0641\u0630 \u0628\u0627\u0632 \u0635\u0648\u0631\u062a\" \/><label for=\"quform_1_63_a40ede_7\" class=\"quform-option-label quform-option-label-1_63_7\"><span class=\"quform-option-text\">\u0645\u0646\u0627\u0641\u0630 \u0628\u0627\u0632 \u0635\u0648\u0631\u062a<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_63[]\" id=\"quform_1_63_a40ede_6\" class=\"quform-field quform-field-checkbox quform-field-1_63 quform-field-1_63_6\" value=\"\u0627\u0644\u062a\u0647\u0627\u0628 \u0648 \u0642\u0631\u0645\u0632\u06cc \u0648 \u062c\u0648\u0634 \u067e\u0633 \u0627\u0632 \u0627\u0635\u0644\u0627\u062d\" \/><label for=\"quform_1_63_a40ede_6\" class=\"quform-option-label quform-option-label-1_63_6\"><span class=\"quform-option-text\">\u0627\u0644\u062a\u0647\u0627\u0628 \u0648 \u0642\u0631\u0645\u0632\u06cc \u0648 \u062c\u0648\u0634 \u067e\u0633 \u0627\u0632 \u0627\u0635\u0644\u0627\u062d<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_63[]\" id=\"quform_1_63_a40ede_9\" class=\"quform-field quform-field-checkbox quform-field-1_63 quform-field-1_63_9\" value=\"\u06a9\u062f\u0631 \u0634\u062f\u0646 \u067e\u0648\u0633\u062a \u0635\u0648\u0631\u062a\" \/><label for=\"quform_1_63_a40ede_9\" class=\"quform-option-label quform-option-label-1_63_9\"><span class=\"quform-option-text\">\u06a9\u062f\u0631 \u0634\u062f\u0646 \u067e\u0648\u0633\u062a \u0635\u0648\u0631\u062a<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_63[]\" id=\"quform_1_63_a40ede_11\" class=\"quform-field quform-field-checkbox quform-field-1_63 quform-field-1_63_11\" value=\"\u06a9\u06a9 \u0648 \u0645\u06a9 \u062d\u0627\u0635\u0644 \u0627\u0632 \u0622\u0641\u062a\u0627\u0628\" \/><label for=\"quform_1_63_a40ede_11\" class=\"quform-option-label quform-option-label-1_63_11\"><span class=\"quform-option-text\">\u06a9\u06a9 \u0648 \u0645\u06a9 \u062d\u0627\u0635\u0644 \u0627\u0632 \u0622\u0641\u062a\u0627\u0628<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_63[]\" id=\"quform_1_63_a40ede_10\" class=\"quform-field quform-field-checkbox quform-field-1_63 quform-field-1_63_10\" value=\"\u062c\u0627\u06cc \u062c\u0648\u0634 \u0648 \u06cc\u0627 \u0632\u062e\u0645\" \/><label for=\"quform_1_63_a40ede_10\" class=\"quform-option-label quform-option-label-1_63_10\"><span class=\"quform-option-text\">\u062c\u0627\u06cc \u062c\u0648\u0634 \u0648 \u06cc\u0627 \u0632\u062e\u0645<\/span><\/label><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-1_67\"><div class=\"quform-element quform-element-checkbox quform-element-1_68 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-inner quform-inner-checkbox quform-inner-1_68\"><div class=\"quform-input quform-input-checkbox quform-input-1_68 quform-cf\"><div class=\"quform-options quform-cf quform-options-block quform-options-simple\"><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_68[]\" id=\"quform_1_68_a40ede_1\" class=\"quform-field quform-field-checkbox quform-field-1_68 quform-field-1_68_1\" value=\"\u062c\u0648\u0634 \u0628\u062f\u0646 ( \u06a9\u0645\u0631\u060c \u062f\u0633\u062a \u0648 ...)\" \/><label for=\"quform_1_68_a40ede_1\" class=\"quform-option-label quform-option-label-1_68_1\"><span class=\"quform-option-text\">\u062c\u0648\u0634 \u0628\u062f\u0646 ( \u06a9\u0645\u0631\u060c \u062f\u0633\u062a \u0648 ...)<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_68[]\" id=\"quform_1_68_a40ede_2\" class=\"quform-field quform-field-checkbox quform-field-1_68 quform-field-1_68_2\" value=\"\u0644\u06a9\u0647 \u0647\u0627 \u0648 \u062a\u06cc\u0631\u06af\u06cc \u0647\u0627\u06cc \u067e\u0648\u0633\u062a \u062f\u0633\u062a \u0648 \u0628\u062f\u0646\" \/><label for=\"quform_1_68_a40ede_2\" class=\"quform-option-label quform-option-label-1_68_2\"><span class=\"quform-option-text\">\u0644\u06a9\u0647 \u0647\u0627 \u0648 \u062a\u06cc\u0631\u06af\u06cc \u0647\u0627\u06cc \u067e\u0648\u0633\u062a \u062f\u0633\u062a \u0648 \u0628\u062f\u0646<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_68[]\" id=\"quform_1_68_a40ede_3\" class=\"quform-field quform-field-checkbox quform-field-1_68 quform-field-1_68_3\" value=\"\u0628\u0648\u06cc \u0646\u0627 \u0645\u0637\u0628\u0648\u0639 \u062a\u0639\u0631\u06cc\u0642 \u0628\u062f\u0646\" \/><label for=\"quform_1_68_a40ede_3\" class=\"quform-option-label quform-option-label-1_68_3\"><span class=\"quform-option-text\">\u0628\u0648\u06cc \u0646\u0627 \u0645\u0637\u0628\u0648\u0639 \u062a\u0639\u0631\u06cc\u0642 \u0628\u062f\u0646<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_68[]\" id=\"quform_1_68_a40ede_6\" class=\"quform-field quform-field-checkbox quform-field-1_68 quform-field-1_68_6\" value=\"\u062e\u0634\u06a9\u06cc \u0648 \u062a\u0631\u06a9 \u06a9\u0641 \u067e\u0627\" \/><label for=\"quform_1_68_a40ede_6\" class=\"quform-option-label quform-option-label-1_68_6\"><span class=\"quform-option-text\">\u062e\u0634\u06a9\u06cc \u0648 \u062a\u0631\u06a9 \u06a9\u0641 \u067e\u0627<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_68[]\" id=\"quform_1_68_a40ede_5\" class=\"quform-field quform-field-checkbox quform-field-1_68 quform-field-1_68_5\" value=\"\u0628\u0648\u06cc \u0628\u062f \u067e\u0627\" \/><label for=\"quform_1_68_a40ede_5\" class=\"quform-option-label quform-option-label-1_68_5\"><span class=\"quform-option-text\">\u0628\u0648\u06cc \u0628\u062f \u067e\u0627<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_68[]\" id=\"quform_1_68_a40ede_4\" class=\"quform-field quform-field-checkbox quform-field-1_68 quform-field-1_68_4\" value=\"\u062e\u0634\u06a9\u06cc \u0648 \u0627\u06af\u0632\u0645\u0627 \u067e\u0648\u0633\u062a \u0628\u062f\u0646\" \/><label for=\"quform_1_68_a40ede_4\" class=\"quform-option-label quform-option-label-1_68_4\"><span class=\"quform-option-text\">\u062e\u0634\u06a9\u06cc \u0648 \u0627\u06af\u0632\u0645\u0627 \u067e\u0648\u0633\u062a \u0628\u062f\u0646<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_68[]\" id=\"quform_1_68_a40ede_8\" class=\"quform-field quform-field-checkbox quform-field-1_68 quform-field-1_68_8\" value=\"\u0627\u062d\u0633\u0627\u0633 \u0634\u0644 \u0634\u062f\u06af\u06cc \u0648 \u0627\u0641\u062a\u0627\u062f\u06af\u06cc \u067e\u0648\u0633\u062a \u0628\u062f\u0646\" \/><label for=\"quform_1_68_a40ede_8\" class=\"quform-option-label quform-option-label-1_68_8\"><span class=\"quform-option-text\">\u0627\u062d\u0633\u0627\u0633 \u0634\u0644 \u0634\u062f\u06af\u06cc \u0648 \u0627\u0641\u062a\u0627\u062f\u06af\u06cc \u067e\u0648\u0633\u062a \u0628\u062f\u0646<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_68[]\" id=\"quform_1_68_a40ede_7\" class=\"quform-field quform-field-checkbox quform-field-1_68 quform-field-1_68_7\" value=\"\u062a\u06cc\u0631\u06af\u06cc\u060c \u067e\u0641 \u0648 \u06cc\u0627 \u0686\u0631\u0648\u06a9 \u062f\u0648\u0631 \u0686\u0634\u0645\" \/><label for=\"quform_1_68_a40ede_7\" class=\"quform-option-label quform-option-label-1_68_7\"><span class=\"quform-option-text\">\u062a\u06cc\u0631\u06af\u06cc\u060c \u067e\u0641 \u0648 \u06cc\u0627 \u0686\u0631\u0648\u06a9 \u062f\u0648\u0631 \u0686\u0634\u0645<\/span><\/label><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-1_64 quform-cf quform-button-style-theme\"><div class=\"quform-button-back quform-button-back-default quform-button-back-1_64\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-back\" value=\"back\"><span class=\"quform-button-text quform-button-back-text\">\u0628\u0631\u06af\u0634\u062a<\/span><\/button><\/div><div class=\"quform-button-next quform-button-next-default quform-button-next-1_64\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-next\" value=\"submit\"><span class=\"quform-button-text quform-button-next-text\">\u0628\u0639\u062f\u06cc<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-page quform-page-69 quform-page-1_69 quform-cf quform-group-style-plain\"><div class=\"quform-page-title-description\"><h4 class=\"quform-page-title\">\u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0631\u0627 \u0631\u0648\u06cc \u0645\u0640\u0640\u0640\u0640\u0648 \u062e\u0648\u062f \u0627\u062d\u0633\u0627\u0633 \u0645\u06cc \u06a9\u0646\u06cc\u062f\u061f<\/h4><p class=\"quform-page-description\">\u00a0\n\u00a0\n\u00a0\n<\/p><\/div><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-row quform-element-row-1_76 quform-2-columns quform-element-row-size-fixed quform-responsive-columns-phone-landscape\"><div class=\"quform-element quform-element-column quform-element-1_77\"><div class=\"quform-element quform-element-checkbox quform-element-1_80 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-inner quform-inner-checkbox quform-inner-1_80\"><div class=\"quform-input quform-input-checkbox quform-input-1_80 quform-cf\"><div class=\"quform-options quform-cf quform-options-block quform-options-simple\"><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_80[]\" id=\"quform_1_80_a40ede_1\" class=\"quform-field quform-field-checkbox quform-field-1_80 quform-field-1_80_1\" value=\"\u06a9\u062f\u0631 \u0634\u062f\u0646 \u0645\u0648\" \/><label for=\"quform_1_80_a40ede_1\" class=\"quform-option-label quform-option-label-1_80_1\"><span class=\"quform-option-text\">\u06a9\u062f\u0631 \u0634\u062f\u0646 \u0645\u0648<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_80[]\" id=\"quform_1_80_a40ede_2\" class=\"quform-field quform-field-checkbox quform-field-1_80 quform-field-1_80_2\" value=\"\u062d\u0627\u0644\u062a \u0646\u06af\u0631\u0641\u062a\u0646 \u0645\u0648\" \/><label for=\"quform_1_80_a40ede_2\" class=\"quform-option-label quform-option-label-1_80_2\"><span class=\"quform-option-text\">\u062d\u0627\u0644\u062a \u0646\u06af\u0631\u0641\u062a\u0646 \u0645\u0648<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_80[]\" id=\"quform_1_80_a40ede_3\" class=\"quform-field quform-field-checkbox quform-field-1_80 quform-field-1_80_3\" value=\"\u0646\u0627\u0632\u06a9\u06cc \u0645\u0648\" \/><label for=\"quform_1_80_a40ede_3\" class=\"quform-option-label quform-option-label-1_80_3\"><span class=\"quform-option-text\">\u0646\u0627\u0632\u06a9\u06cc \u0645\u0648<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_80[]\" id=\"quform_1_80_a40ede_4\" class=\"quform-field quform-field-checkbox quform-field-1_80 quform-field-1_80_4\" value=\"\u0631\u06cc\u0632\u0634 \u0645\u0648\" \/><label for=\"quform_1_80_a40ede_4\" class=\"quform-option-label quform-option-label-1_80_4\"><span class=\"quform-option-text\">\u0631\u06cc\u0632\u0634 \u0645\u0648<\/span><\/label><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-1_78\"><div class=\"quform-element quform-element-checkbox quform-element-1_79 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-inner quform-inner-checkbox quform-inner-1_79\"><div class=\"quform-input quform-input-checkbox quform-input-1_79 quform-cf\"><div class=\"quform-options quform-cf quform-options-block quform-options-simple\"><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_79[]\" id=\"quform_1_79_a40ede_1\" class=\"quform-field quform-field-checkbox quform-field-1_79 quform-field-1_79_1\" value=\"\u0686\u0631\u0628 \u0628\u0648\u062f\u0646 \u0645\u0648 \u0648 \u06cc\u0627 \u06a9\u0641 \u0633\u0631\" \/><label for=\"quform_1_79_a40ede_1\" class=\"quform-option-label quform-option-label-1_79_1\"><span class=\"quform-option-text\">\u0686\u0631\u0628 \u0628\u0648\u062f\u0646 \u0645\u0648 \u0648 \u06cc\u0627 \u06a9\u0641 \u0633\u0631<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_79[]\" id=\"quform_1_79_a40ede_2\" class=\"quform-field quform-field-checkbox quform-field-1_79 quform-field-1_79_2\" value=\"\u0634\u0648\u0631\u0647 \u0645\u0648 \u0648 \u06cc\u0627 \u06a9\u0641 \u0633\u0631\" \/><label for=\"quform_1_79_a40ede_2\" class=\"quform-option-label quform-option-label-1_79_2\"><span class=\"quform-option-text\">\u0634\u0648\u0631\u0647 \u0645\u0648 \u0648 \u06cc\u0627 \u06a9\u0641 \u0633\u0631<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_79[]\" id=\"quform_1_79_a40ede_3\" class=\"quform-field quform-field-checkbox quform-field-1_79 quform-field-1_79_3\" value=\"\u062e\u0634\u06a9\u06cc \u0645\u0648 \u0648 \u06cc\u0627 \u06a9\u0641 \u0633\u0631\" \/><label for=\"quform_1_79_a40ede_3\" class=\"quform-option-label quform-option-label-1_79_3\"><span class=\"quform-option-text\">\u062e\u0634\u06a9\u06cc \u0645\u0648 \u0648 \u06cc\u0627 \u06a9\u0641 \u0633\u0631<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_79[]\" id=\"quform_1_79_a40ede_4\" class=\"quform-field quform-field-checkbox quform-field-1_79 quform-field-1_79_4\" value=\"\u067e\u0648\u0633\u062a\u0647 \u067e\u0648\u0633\u062a\u0647 \u0634\u062f\u0646 \u06a9\u0641 \u0633\u0631\" \/><label for=\"quform_1_79_a40ede_4\" class=\"quform-option-label quform-option-label-1_79_4\"><span class=\"quform-option-text\">\u067e\u0648\u0633\u062a\u0647 \u067e\u0648\u0633\u062a\u0647 \u0634\u062f\u0646 \u06a9\u0641 \u0633\u0631<\/span><\/label><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-1_75 quform-cf quform-button-style-theme\"><div class=\"quform-button-back quform-button-back-default quform-button-back-1_75\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-back\" value=\"back\"><span class=\"quform-button-text quform-button-back-text\">\u0628\u0631\u06af\u0634\u062a<\/span><\/button><\/div><div class=\"quform-button-next quform-button-next-default quform-button-next-1_75\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-next\" value=\"submit\"><span class=\"quform-button-text quform-button-next-text\">\u0628\u0639\u062f\u06cc<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-page quform-page-81 quform-page-1_81 quform-cf quform-group-style-plain quform-last-page\"><div class=\"quform-page-title-description\"><h4 class=\"quform-page-title\">\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u0641\u0631\u0642\u0647<\/h4><p class=\"quform-page-description\">\u062a\u0645\u0627\u06cc\u0644 \u062f\u0627\u0631\u06cc\u062f \u0627\u0632 \u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0647\u062f\u0627\u0634\u062a\u06cc \u0648 \u0622\u0631\u0627\u06cc\u0634\u06cc \u0632\u06cc\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f\u061f\n\u00a0\n\u00a0<\/p><\/div><div class=\"quform-child-elements\"><div class=\"quform-element quform-element-row quform-element-row-1_82 quform-2-columns quform-element-row-size-fixed quform-responsive-columns-phone-landscape\"><div class=\"quform-element quform-element-column quform-element-1_83\"><div class=\"quform-element quform-element-checkbox quform-element-1_84 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-inner quform-inner-checkbox quform-inner-1_84\"><div class=\"quform-input quform-input-checkbox quform-input-1_84 quform-cf\"><div class=\"quform-options quform-cf quform-options-block quform-options-simple\"><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_84[]\" id=\"quform_1_84_a40ede_1\" class=\"quform-field quform-field-checkbox quform-field-1_84 quform-field-1_84_1\" value=\"\u06a9\u0631\u0645 \u067e\u0648\u062f\u0631\" \/><label for=\"quform_1_84_a40ede_1\" class=\"quform-option-label quform-option-label-1_84_1\"><span class=\"quform-option-text\">\u06a9\u0631\u0645 \u067e\u0648\u062f\u0631<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_84[]\" id=\"quform_1_84_a40ede_2\" class=\"quform-field quform-field-checkbox quform-field-1_84 quform-field-1_84_2\" value=\"\u067e\u0646\u06a9\u06cc\u06a9\" \/><label for=\"quform_1_84_a40ede_2\" class=\"quform-option-label quform-option-label-1_84_2\"><span class=\"quform-option-text\">\u067e\u0646\u06a9\u06cc\u06a9<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_84[]\" id=\"quform_1_84_a40ede_3\" class=\"quform-field quform-field-checkbox quform-field-1_84 quform-field-1_84_3\" value=\"\u0631\u0698\u06af\u0648\u0646\u0647\" \/><label for=\"quform_1_84_a40ede_3\" class=\"quform-option-label quform-option-label-1_84_3\"><span class=\"quform-option-text\">\u0631\u0698\u06af\u0648\u0646\u0647<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_84[]\" id=\"quform_1_84_a40ede_4\" class=\"quform-field quform-field-checkbox quform-field-1_84 quform-field-1_84_4\" value=\"\u0631\u06cc\u0645\u0644\" \/><label for=\"quform_1_84_a40ede_4\" class=\"quform-option-label quform-option-label-1_84_4\"><span class=\"quform-option-text\">\u0631\u06cc\u0645\u0644<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_84[]\" id=\"quform_1_84_a40ede_5\" class=\"quform-field quform-field-checkbox quform-field-1_84 quform-field-1_84_5\" value=\"\u0647\u0627\u0634\u0648\u0631 \u0627\u0628\u0631\u0648\" \/><label for=\"quform_1_84_a40ede_5\" class=\"quform-option-label quform-option-label-1_84_5\"><span class=\"quform-option-text\">\u0647\u0627\u0634\u0648\u0631 \u0627\u0628\u0631\u0648<\/span><\/label><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-column quform-element-1_85\"><div class=\"quform-element quform-element-checkbox quform-element-1_86 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-inner quform-inner-checkbox quform-inner-1_86\"><div class=\"quform-input quform-input-checkbox quform-input-1_86 quform-cf\"><div class=\"quform-options quform-cf quform-options-block quform-options-simple\"><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_86[]\" id=\"quform_1_86_a40ede_1\" class=\"quform-field quform-field-checkbox quform-field-1_86 quform-field-1_86_1\" value=\"\u062f\u0633\u062a\u0645\u0627\u0644 \u06a9\u0627\u063a\u0630\u06cc \u06a9\u06cc\u0641\u06cc\u062a A+ \u0635\u0627\u062f\u0631\u0627\u062a\u06cc\" \/><label for=\"quform_1_86_a40ede_1\" class=\"quform-option-label quform-option-label-1_86_1\"><span class=\"quform-option-text\">\u062f\u0633\u062a\u0645\u0627\u0644 \u06a9\u0627\u063a\u0630\u06cc \u06a9\u06cc\u0641\u06cc\u062a A+ \u0635\u0627\u062f\u0631\u0627\u062a\u06cc<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_86[]\" id=\"quform_1_86_a40ede_2\" class=\"quform-field quform-field-checkbox quform-field-1_86 quform-field-1_86_2\" value=\"\u062f\u0633\u062a\u0645\u0627\u0644 \u0645\u0631\u0637\u0648\u0628 \u0622\u0631\u0627\u06cc\u0634 \u067e\u0627\u06a9 \u06a9\u0646 \u0628\u062f\u0648\u0646 \u0627\u0644\u06a9\u0644\" \/><label for=\"quform_1_86_a40ede_2\" class=\"quform-option-label quform-option-label-1_86_2\"><span class=\"quform-option-text\">\u062f\u0633\u062a\u0645\u0627\u0644 \u0645\u0631\u0637\u0648\u0628 \u0622\u0631\u0627\u06cc\u0634 \u067e\u0627\u06a9 \u06a9\u0646 \u0628\u062f\u0648\u0646 \u0627\u0644\u06a9\u0644<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_86[]\" id=\"quform_1_86_a40ede_3\" class=\"quform-field quform-field-checkbox quform-field-1_86 quform-field-1_86_3\" value=\"\u0646\u0648\u0627\u0631\u0628\u0647\u062f\u0627\u0634\u062a\u06cc \u0635\u0627\u062f\u0631\u0627\u062a\u06cc \u0645\u0639\u0637\u0631 \u0628\u0627 \u062c\u0630\u0628 \u0628\u0627\u0644\u0627\" \/><label for=\"quform_1_86_a40ede_3\" class=\"quform-option-label quform-option-label-1_86_3\"><span class=\"quform-option-text\">\u0646\u0648\u0627\u0631\u0628\u0647\u062f\u0627\u0634\u062a\u06cc \u0635\u0627\u062f\u0631\u0627\u062a\u06cc \u0645\u0639\u0637\u0631 \u0628\u0627 \u062c\u0630\u0628 \u0628\u0627\u0644\u0627<\/span><\/label><\/div><div class=\"quform-option\"><input type=\"checkbox\" name=\"quform_1_86[]\" id=\"quform_1_86_a40ede_4\" class=\"quform-field quform-field-checkbox quform-field-1_86 quform-field-1_86_4\" value=\"\u0628\u0627\u062f\u06cc \u0627\u0633\u067e\u0644\u0634 ( \u0627\u0633\u067e\u0631\u06cc \u0628\u062f\u0646 \u0622\u0628\u0631\u0633\u0627\u0646)\" \/><label for=\"quform_1_86_a40ede_4\" class=\"quform-option-label quform-option-label-1_86_4\"><span class=\"quform-option-text\">\u0628\u0627\u062f\u06cc \u0627\u0633\u067e\u0644\u0634 ( \u0627\u0633\u067e\u0631\u06cc \u0628\u062f\u0646 \u0622\u0628\u0631\u0633\u0627\u0646)<\/span><\/label><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-select quform-element-1_88 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_88\"><label class=\"quform-label-text\" for=\"quform_1_88_a40ede\">\u0622\u06cc\u0627 \u062a\u0645\u0627\u06cc\u0644 \u062f\u0627\u0631\u06cc\u062f \u0627\u062e\u0628\u0627\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062c\u062f\u06cc\u062f \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0627\u0631\u0633\u0627\u0644 \u0634\u0648\u062f\u061f<\/label><\/div><div class=\"quform-inner quform-inner-select quform-inner-1_88\"><div class=\"quform-input quform-input-select quform-input-1_88 quform-cf\"><select id=\"quform_1_88_a40ede\" name=\"quform_1_88\" class=\"quform-field quform-field-select quform-field-1_88\"><option value=\"\" selected=\"selected\">\u0644\u0637\u0641\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f<\/option><option value=\"\u0628\u0644\u06cc\">\u0628\u0644\u06cc<\/option><option value=\"\u062e\u06cc\u0631\">\u062e\u06cc\u0631<\/option><\/select><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-select quform-element-1_90 quform-cf quform-element-optional\"><div class=\"quform-spacer\"><div class=\"quform-label quform-label-1_90\"><label class=\"quform-label-text\" for=\"quform_1_90_a40ede\">\u0622\u06cc\u0627 \u062a\u0645\u0627\u06cc\u0644 \u062f\u0627\u0631\u06cc\u062f \u0628\u0627 \u0641\u0631\u0635\u062a \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631 \u0634\u0631\u06a9\u062a \u0645\u0627 \u0622\u0634\u0646\u0627 \u0634\u0648\u06cc\u062f\u061f<\/label><\/div><div class=\"quform-inner quform-inner-select quform-inner-1_90\"><div class=\"quform-input quform-input-select quform-input-1_90 quform-cf\"><select id=\"quform_1_90_a40ede\" name=\"quform_1_90\" class=\"quform-field quform-field-select quform-field-1_90\"><option value=\"\" selected=\"selected\">\u0644\u0637\u0641\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f<\/option><option value=\"\u0628\u0644\u06cc\">\u0628\u0644\u06cc<\/option><option value=\"\u062e\u06cc\u0631\">\u062e\u06cc\u0631<\/option><\/select><\/div><\/div><\/div><\/div><div class=\"quform-element quform-element-submit quform-element-1_87 quform-cf quform-button-style-theme\"><div class=\"quform-button-back quform-button-back-default quform-button-back-1_87\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-back\" value=\"back\"><span class=\"quform-button-text quform-button-back-text\">\u0628\u0631\u06af\u0634\u062a<\/span><\/button><\/div><div class=\"quform-button-submit quform-button-submit-default quform-button-submit-1_87\"><button name=\"quform_submit\" type=\"submit\" class=\"quform-submit\" value=\"submit\"><span class=\"quform-button-text quform-button-submit-text\">\u0627\u0631\u0633\u0627\u0644<\/span><\/button><\/div><div class=\"quform-loading quform-loading-position-left quform-loading-type-spinner-1\"><div class=\"quform-loading-inner\"><div class=\"quform-loading-spinner\"><div class=\"quform-loading-spinner-inner\"><\/div><\/div><\/div><\/div><\/div><div class=\"quform-element-tree\"><label for=\"quform_1_0_a40ede\">\u0627\u06cc\u0646 \u0642\u0633\u0645\u062a \u0646\u0628\u0627\u06cc\u062f \u062e\u0627\u0644\u06cc \u0631\u0647\u0627 \u0634\u0648\u062f.<\/label><input type=\"text\" id=\"quform_1_0_a40ede\" name=\"quform_1_0\" class=\"quform-field quform-field-tree quform-field-1_0\" tabindex=\"-1\" autocomplete=\"off\" \/><\/div><\/div><\/div><\/div><\/div><\/form><\/div>\n<p><span style=\"font-size: 14pt;\"><strong><span style=\"color: #ff0000;\">\u0686\u0646\u0627\u0646\u0686\u0647 \u0645\u0634\u06a9\u0644 \u0648 \u06cc\u0627 \u0647\u0631 \u0639\u0627\u0631\u0636\u0647 \u0648 \u0647\u0631 \u06af\u0648\u0646\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0627\u0631\u06cc\u062f\u060c \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0648 \u062f\u0631\u06cc\u0627\u0641\u062a \u062f\u0627\u0631\u0648 \u062c\u0647\u062a \u0648\u06cc\u0632\u06cc\u062a \u0628\u0647 \u0645\u062a\u062e\u0635\u0635\u06cc\u0646 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f!<\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #008000; font-size: 14pt;\">\u062f\u0631 \u0627\u06cc\u0646 \u0641\u0631\u0645 \u0645\u0634\u0627\u0648\u0631\u0647 \u062a\u0646\u0647\u0627 \u0631\u0648\u062a\u06cc\u0646 \u0645\u0631\u0627\u0642\u0628\u062a \u0627\u0632 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648 \u0648 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0622\u0631\u0627\u06cc\u0634\u06cc \u0648 \u0628\u0647\u062f\u0627\u0634\u062a\u06cc \u0645\u0646\u0627\u0633\u0628 \u067e\u0648\u0633\u062a \u0634\u0645\u0627 \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc \u0634\u0648\u062f.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0686\u0646\u0627\u0646\u0686\u0647 \u0645\u0634\u06a9\u0644 \u0648 \u06cc\u0627 \u0647\u0631 \u0639\u0627\u0631\u0636\u0647 \u0648 \u0647\u0631 \u06af\u0648\u0646\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0627\u0631\u06cc\u062f\u060c \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0648 \u062f\u0631\u06cc\u0627\u0641\u062a \u062f\u0627\u0631\u0648 \u062c\u0647\u062a \u0648\u06cc\u0632\u06cc\u062a \u0628\u0647 \u0645\u062a\u062e\u0635\u0635\u06cc\u0646<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1486","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0641\u0631\u0645 \u0645\u0634\u0627\u0648\u0631\u0647 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648 | \u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beskin.ir\/shop\/form\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0641\u0631\u0645 \u0645\u0634\u0627\u0648\u0631\u0647 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648\" \/>\n<meta property=\"og:description\" content=\"\u0686\u0646\u0627\u0646\u0686\u0647 \u0645\u0634\u06a9\u0644 \u0648 \u06cc\u0627 \u0647\u0631 \u0639\u0627\u0631\u0636\u0647 \u0648 \u0647\u0631 \u06af\u0648\u0646\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0627\u0631\u06cc\u062f\u060c \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0648 \u062f\u0631\u06cc\u0627\u0641\u062a \u062f\u0627\u0631\u0648 \u062c\u0647\u062a \u0648\u06cc\u0632\u06cc\u062a \u0628\u0647 \u0645\u062a\u062e\u0635\u0635\u06cc\u0646\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beskin.ir\/shop\/form\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T09:05:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/form\\\/\",\"url\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/form\\\/\",\"name\":\"\u0641\u0631\u0645 \u0645\u0634\u0627\u0648\u0631\u0647 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648 | \u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/#website\"},\"datePublished\":\"2020-12-04T17:51:57+00:00\",\"dateModified\":\"2026-04-13T09:05:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/form\\\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beskin.ir\\\/shop\\\/form\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/form\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0641\u0631\u0645 \u0645\u0634\u0627\u0648\u0631\u0647 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/#website\",\"url\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/\",\"name\":\"\u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627\",\"description\":\"\u0646\u0645\u0627\u06cc\u0646\u062f\u06af\u06cc \u0641\u0631\u0648\u0634 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0644\u062f\u0648\u0631\u0627 \u0628\u0627 \u062a\u062e\u0641\u06cc\u0641 \u0647\u0645\u06cc\u0634\u06af\u06cc\",\"publisher\":{\"@id\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/#organization\",\"name\":\"\u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627\",\"url\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/beskin-new-logo3.png\",\"contentUrl\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/beskin-new-logo3.png\",\"width\":385,\"height\":176,\"caption\":\"\u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627\"},\"image\":{\"@id\":\"https:\\\/\\\/beskin.ir\\\/shop\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0641\u0631\u0645 \u0645\u0634\u0627\u0648\u0631\u0647 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648 | \u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beskin.ir\/shop\/form\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0641\u0631\u0645 \u0645\u0634\u0627\u0648\u0631\u0647 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648","og_description":"\u0686\u0646\u0627\u0646\u0686\u0647 \u0645\u0634\u06a9\u0644 \u0648 \u06cc\u0627 \u0647\u0631 \u0639\u0627\u0631\u0636\u0647 \u0648 \u0647\u0631 \u06af\u0648\u0646\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0627\u0631\u06cc\u062f\u060c \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0648 \u062f\u0631\u06cc\u0627\u0641\u062a \u062f\u0627\u0631\u0648 \u062c\u0647\u062a \u0648\u06cc\u0632\u06cc\u062a \u0628\u0647 \u0645\u062a\u062e\u0635\u0635\u06cc\u0646","og_url":"https:\/\/beskin.ir\/shop\/form\/","og_site_name":"\u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627","article_modified_time":"2026-04-13T09:05:36+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beskin.ir\/shop\/form\/","url":"https:\/\/beskin.ir\/shop\/form\/","name":"\u0641\u0631\u0645 \u0645\u0634\u0627\u0648\u0631\u0647 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648 | \u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627","isPartOf":{"@id":"https:\/\/beskin.ir\/shop\/#website"},"datePublished":"2020-12-04T17:51:57+00:00","dateModified":"2026-04-13T09:05:36+00:00","breadcrumb":{"@id":"https:\/\/beskin.ir\/shop\/form\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beskin.ir\/shop\/form\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beskin.ir\/shop\/form\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/beskin.ir\/shop\/"},{"@type":"ListItem","position":2,"name":"\u0641\u0631\u0645 \u0645\u0634\u0627\u0648\u0631\u0647 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648"}]},{"@type":"WebSite","@id":"https:\/\/beskin.ir\/shop\/#website","url":"https:\/\/beskin.ir\/shop\/","name":"\u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627","description":"\u0646\u0645\u0627\u06cc\u0646\u062f\u06af\u06cc \u0641\u0631\u0648\u0634 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0644\u062f\u0648\u0631\u0627 \u0628\u0627 \u062a\u062e\u0641\u06cc\u0641 \u0647\u0645\u06cc\u0634\u06af\u06cc","publisher":{"@id":"https:\/\/beskin.ir\/shop\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beskin.ir\/shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/beskin.ir\/shop\/#organization","name":"\u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627","url":"https:\/\/beskin.ir\/shop\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/beskin.ir\/shop\/#\/schema\/logo\/image\/","url":"https:\/\/beskin.ir\/shop\/wp-content\/uploads\/2026\/04\/beskin-new-logo3.png","contentUrl":"https:\/\/beskin.ir\/shop\/wp-content\/uploads\/2026\/04\/beskin-new-logo3.png","width":385,"height":176,"caption":"\u0628\u0633\u06a9\u06cc\u0646 \u0644\u062f\u0648\u0631\u0627"},"image":{"@id":"https:\/\/beskin.ir\/shop\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/beskin.ir\/shop\/wp-json\/wp\/v2\/pages\/1486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beskin.ir\/shop\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/beskin.ir\/shop\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/beskin.ir\/shop\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beskin.ir\/shop\/wp-json\/wp\/v2\/comments?post=1486"}],"version-history":[{"count":0,"href":"https:\/\/beskin.ir\/shop\/wp-json\/wp\/v2\/pages\/1486\/revisions"}],"wp:attachment":[{"href":"https:\/\/beskin.ir\/shop\/wp-json\/wp\/v2\/media?parent=1486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}